{"id":7921,"date":"2016-06-14T16:02:29","date_gmt":"2016-06-14T14:02:29","guid":{"rendered":"http:\/\/www.irbab-kbivb.be\/fr\/?p=7921"},"modified":"2016-06-14T16:26:40","modified_gmt":"2016-06-14T14:26:40","slug":"presence-pseudomonas-mais-traitement-necessaire","status":"publish","type":"post","link":"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/","title":{"rendered":"Pr\u00e9sence de pseudomonas mais pas de traitement n\u00e9cessaire"},"content":{"rendered":"<p><a href=\"https:\/\/www.irbab-kbivb.be\/wp-content\/uploads\/2016\/06\/pseudomonas.jpg\" rel=\"attachment wp-att-7895\"><img loading=\"lazy\" decoding=\"async\" class=\"rounded alignleft wp-image-7895 size-medium\" src=\"https:\/\/www.irbab-kbivb.be\/wp-content\/uploads\/2016\/06\/pseudomonas-300x211.jpg\" alt=\"pseudomonas\" width=\"300\" height=\"211\" srcset=\"https:\/\/www.irbab-kbivb.be\/wp-content\/uploads\/2016\/06\/pseudomonas-300x211.jpg 300w, https:\/\/www.irbab-kbivb.be\/wp-content\/uploads\/2016\/06\/pseudomonas-768x540.jpg 768w, https:\/\/www.irbab-kbivb.be\/wp-content\/uploads\/2016\/06\/pseudomonas.jpg 1024w, https:\/\/www.irbab-kbivb.be\/wp-content\/uploads\/2016\/06\/pseudomonas-810x570.jpg 810w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Aucune intervention n&rsquo;est \u00e0 envisager contre <u>cette bact\u00e9rie<\/u>. La maladie disparaitra avec le retour du temps sec et chaud. Les feuilles pr\u00e9sentent des taches fonc\u00e9es et des n\u00e9croses de forme et dimensions irr\u00e9guli\u00e8res (1-6 mm), de couleur grise dans le centre et avec un bord large, fonc\u00e9 et net. Les bords des feuilles brunissent et se dess\u00e8chent. La maladie est favoris\u00e9e par les conditions humides actuelles.L&rsquo;intensit\u00e9 des sympt\u00f4mes peut varier en fonction de la parcelle, de l&rsquo;intensit\u00e9 des averses (les blessures caus\u00e9es par le gr\u00eale ou les pluies intenses sont des portes d&rsquo;entr\u00e9e pour la bact\u00e9rie), de la vari\u00e9t\u00e9,&#8230;<br \/>\nModule &ldquo;<a href=\"http:\/\/www.int-koop.de\/schaeden\/mod_liz_schaeden_texttafel\/tafel_id\/109\/lang\/fr_irbab\/partner\/irbab\/index.html\">Identification des maladies et ravageurs<\/a>&rdquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aucune intervention n&rsquo;est \u00e0 envisager contre cette bact\u00e9rie. La maladie disparaitra avec le retour du temps sec et chaud. Les feuilles pr\u00e9sentent des taches fonc\u00e9es et des n\u00e9croses de forme et dimensions irr\u00e9guli\u00e8res (1-6 mm), de couleur grise dans le centre et avec un bord large, fonc\u00e9 et net. Les bords des feuilles brunissent et [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7895,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":3,"footnotes":""},"categories":[221],"tags":[243],"class_list":["post-7921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-maladies-foliaires","tag-messages"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00e9sence de pseudomonas mais pas de traitement n\u00e9cessaire - IRBAB-KBIVB<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e9sence de pseudomonas mais pas de traitement n\u00e9cessaire - IRBAB-KBIVB\" \/>\n<meta property=\"og:description\" content=\"Aucune intervention n&rsquo;est \u00e0 envisager contre cette bact\u00e9rie. La maladie disparaitra avec le retour du temps sec et chaud. Les feuilles pr\u00e9sentent des taches fonc\u00e9es et des n\u00e9croses de forme et dimensions irr\u00e9guli\u00e8res (1-6 mm), de couleur grise dans le centre et avec un bord large, fonc\u00e9 et net. Les bords des feuilles brunissent et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/\" \/>\n<meta property=\"og:site_name\" content=\"IRBAB-KBIVB\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-14T14:02:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-14T14:26:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irbab-kbivb.be\/wp-content\/uploads\/2016\/06\/pseudomonas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/presence-pseudomonas-mais-traitement-necessaire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/presence-pseudomonas-mais-traitement-necessaire\\\/\"},\"author\":{\"name\":\"Marion\",\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/#\\\/schema\\\/person\\\/dad6fe34d3ac93cce3720797f132a2e5\"},\"headline\":\"Pr\u00e9sence de pseudomonas mais pas de traitement n\u00e9cessaire\",\"datePublished\":\"2016-06-14T14:02:29+00:00\",\"dateModified\":\"2016-06-14T14:26:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/presence-pseudomonas-mais-traitement-necessaire\\\/\"},\"wordCount\":139,\"image\":{\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/presence-pseudomonas-mais-traitement-necessaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/pseudomonas.jpg\",\"keywords\":[\"Messages\"],\"articleSection\":[\"Maladies foliaires\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/presence-pseudomonas-mais-traitement-necessaire\\\/\",\"url\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/presence-pseudomonas-mais-traitement-necessaire\\\/\",\"name\":\"Pr\u00e9sence de pseudomonas mais pas de traitement n\u00e9cessaire - IRBAB-KBIVB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/presence-pseudomonas-mais-traitement-necessaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/presence-pseudomonas-mais-traitement-necessaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/pseudomonas.jpg\",\"datePublished\":\"2016-06-14T14:02:29+00:00\",\"dateModified\":\"2016-06-14T14:26:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/#\\\/schema\\\/person\\\/dad6fe34d3ac93cce3720797f132a2e5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/presence-pseudomonas-mais-traitement-necessaire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/presence-pseudomonas-mais-traitement-necessaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/presence-pseudomonas-mais-traitement-necessaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/pseudomonas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/pseudomonas.jpg\",\"width\":1024,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/presence-pseudomonas-mais-traitement-necessaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Betterave\",\"item\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/category\\\/betterave\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Protection des plantes\",\"item\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/category\\\/betterave\\\/protection-des-plantes\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Maladies foliaires\",\"item\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/category\\\/betterave\\\/protection-des-plantes\\\/maladies-foliaires\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Pr\u00e9sence de pseudomonas mais pas de traitement n\u00e9cessaire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/#website\",\"url\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/\",\"name\":\"IRBAB-KBIVB\",\"description\":\"Koninklijk Belgisch Instituut tot Verbetering van de Biet vzw | Institut Royal Belge pour l&#039;Am\u00e9lioration de la Betterave asbl\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/#\\\/schema\\\/person\\\/dad6fe34d3ac93cce3720797f132a2e5\",\"name\":\"Marion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05aacf3b7aaf804eb748ec4466641d1174d8526a14e65b425d918689da98856a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05aacf3b7aaf804eb748ec4466641d1174d8526a14e65b425d918689da98856a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05aacf3b7aaf804eb748ec4466641d1174d8526a14e65b425d918689da98856a?s=96&d=mm&r=g\",\"caption\":\"Marion\"},\"url\":\"https:\\\/\\\/www.irbab-kbivb.be\\\/fr\\\/author\\\/anja\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00e9sence de pseudomonas mais pas de traitement n\u00e9cessaire - IRBAB-KBIVB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/","og_locale":"fr_FR","og_type":"article","og_title":"Pr\u00e9sence de pseudomonas mais pas de traitement n\u00e9cessaire - IRBAB-KBIVB","og_description":"Aucune intervention n&rsquo;est \u00e0 envisager contre cette bact\u00e9rie. La maladie disparaitra avec le retour du temps sec et chaud. Les feuilles pr\u00e9sentent des taches fonc\u00e9es et des n\u00e9croses de forme et dimensions irr\u00e9guli\u00e8res (1-6 mm), de couleur grise dans le centre et avec un bord large, fonc\u00e9 et net. Les bords des feuilles brunissent et [&hellip;]","og_url":"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/","og_site_name":"IRBAB-KBIVB","article_published_time":"2016-06-14T14:02:29+00:00","article_modified_time":"2016-06-14T14:26:40+00:00","og_image":[{"width":1024,"height":720,"url":"https:\/\/www.irbab-kbivb.be\/wp-content\/uploads\/2016\/06\/pseudomonas.jpg","type":"image\/jpeg"}],"author":"Marion","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marion","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/#article","isPartOf":{"@id":"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/"},"author":{"name":"Marion","@id":"https:\/\/www.irbab-kbivb.be\/#\/schema\/person\/dad6fe34d3ac93cce3720797f132a2e5"},"headline":"Pr\u00e9sence de pseudomonas mais pas de traitement n\u00e9cessaire","datePublished":"2016-06-14T14:02:29+00:00","dateModified":"2016-06-14T14:26:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/"},"wordCount":139,"image":{"@id":"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irbab-kbivb.be\/wp-content\/uploads\/2016\/06\/pseudomonas.jpg","keywords":["Messages"],"articleSection":["Maladies foliaires"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/","url":"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/","name":"Pr\u00e9sence de pseudomonas mais pas de traitement n\u00e9cessaire - IRBAB-KBIVB","isPartOf":{"@id":"https:\/\/www.irbab-kbivb.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/#primaryimage"},"image":{"@id":"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irbab-kbivb.be\/wp-content\/uploads\/2016\/06\/pseudomonas.jpg","datePublished":"2016-06-14T14:02:29+00:00","dateModified":"2016-06-14T14:26:40+00:00","author":{"@id":"https:\/\/www.irbab-kbivb.be\/#\/schema\/person\/dad6fe34d3ac93cce3720797f132a2e5"},"breadcrumb":{"@id":"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/#primaryimage","url":"https:\/\/www.irbab-kbivb.be\/wp-content\/uploads\/2016\/06\/pseudomonas.jpg","contentUrl":"https:\/\/www.irbab-kbivb.be\/wp-content\/uploads\/2016\/06\/pseudomonas.jpg","width":1024,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.irbab-kbivb.be\/fr\/presence-pseudomonas-mais-traitement-necessaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irbab-kbivb.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Betterave","item":"https:\/\/www.irbab-kbivb.be\/fr\/category\/betterave\/"},{"@type":"ListItem","position":3,"name":"Protection des plantes","item":"https:\/\/www.irbab-kbivb.be\/fr\/category\/betterave\/protection-des-plantes\/"},{"@type":"ListItem","position":4,"name":"Maladies foliaires","item":"https:\/\/www.irbab-kbivb.be\/fr\/category\/betterave\/protection-des-plantes\/maladies-foliaires\/"},{"@type":"ListItem","position":5,"name":"Pr\u00e9sence de pseudomonas mais pas de traitement n\u00e9cessaire"}]},{"@type":"WebSite","@id":"https:\/\/www.irbab-kbivb.be\/#website","url":"https:\/\/www.irbab-kbivb.be\/","name":"IRBAB-KBIVB","description":"Koninklijk Belgisch Instituut tot Verbetering van de Biet vzw | Institut Royal Belge pour l&#039;Am\u00e9lioration de la Betterave asbl","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irbab-kbivb.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.irbab-kbivb.be\/#\/schema\/person\/dad6fe34d3ac93cce3720797f132a2e5","name":"Marion","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/05aacf3b7aaf804eb748ec4466641d1174d8526a14e65b425d918689da98856a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05aacf3b7aaf804eb748ec4466641d1174d8526a14e65b425d918689da98856a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05aacf3b7aaf804eb748ec4466641d1174d8526a14e65b425d918689da98856a?s=96&d=mm&r=g","caption":"Marion"},"url":"https:\/\/www.irbab-kbivb.be\/fr\/author\/anja\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irbab-kbivb.be\/fr\/wp-json\/wp\/v2\/posts\/7921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irbab-kbivb.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irbab-kbivb.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irbab-kbivb.be\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irbab-kbivb.be\/fr\/wp-json\/wp\/v2\/comments?post=7921"}],"version-history":[{"count":2,"href":"https:\/\/www.irbab-kbivb.be\/fr\/wp-json\/wp\/v2\/posts\/7921\/revisions"}],"predecessor-version":[{"id":7928,"href":"https:\/\/www.irbab-kbivb.be\/fr\/wp-json\/wp\/v2\/posts\/7921\/revisions\/7928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irbab-kbivb.be\/fr\/wp-json\/wp\/v2\/media\/7895"}],"wp:attachment":[{"href":"https:\/\/www.irbab-kbivb.be\/fr\/wp-json\/wp\/v2\/media?parent=7921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irbab-kbivb.be\/fr\/wp-json\/wp\/v2\/categories?post=7921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irbab-kbivb.be\/fr\/wp-json\/wp\/v2\/tags?post=7921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}